{"id":139046,"date":"2024-01-29T17:22:55","date_gmt":"2024-01-29T16:22:55","guid":{"rendered":"https:\/\/www.wscad.com\/?page_id=139046"},"modified":"2026-02-24T13:19:06","modified_gmt":"2026-02-24T12:19:06","slug":"electrical-cad-software-comparsion","status":"publish","type":"page","link":"https:\/\/www.wscad.com\/en\/lp\/electrical-cad-software-comparsion\/","title":{"rendered":"Electrical CAD software comparsion"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;0&#8243; bottom_margin=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column top_padding_desktop=&#8221;8%&#8221; left_padding_desktop=&#8221;10%&#8221; top_padding_tablet=&#8221;5%&#8221; bottom_padding_tablet=&#8221;5%&#8221; left_padding_tablet=&#8221;5%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;0px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;lp-buehne_txt&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; column_padding_type=&#8221;advanced&#8221;][vc_column_text css=&#8221;.vc_custom_1706545360810{margin-bottom: 6px !important;}&#8221;]\n<h3 style=\"font-weight: 300 !important;\">Why ELECTRIX is the better solution<\/h3>\n[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1706545343933{margin-bottom: 40px !important;}&#8221;]\n<h1>Electrical CAD software comparison<\/h1>\n[\/vc_column_text]<div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-check\" data-animation=\"false\" data-animation-delay=\"0\" data-color=\"extra-color-1\" data-spacing=\"25px\" data-alignment=\"left\"> \n<div class=\"wpb_text_column wpb_content_element wpb_animate_when_almost_visible wpb_fadeInRight fadeInRight feature animated wpb_start_animation\">\n<div class=\"wpb_wrapper\">\n<ul>\n<li>Super fast &#8211; save up to 70% of your engineering time<\/li>\n<li>Intuitive and easy to use<\/li>\n<li>Excellent price\/performance than comparable electrical CAD software<\/li>\n<\/ul>\n<\/div>\n<\/div>\n <\/div>[nectar_btn size=&#8221;jumbo&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Extra-Color-1&#8243; solid_text_color_override=&#8221;#000000&#8243; icon_family=&#8221;fontawesome&#8221; text=&#8221;Try the free demo version now!&#8221; margin_top=&#8221;30&#8243; url=&#8221;#demo&#8221; icon_fontawesome=&#8221;fa fa-play&#8221;][image_with_animation image_url=&#8221;138639&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; margin_top=&#8221;30&#8243; el_class=&#8221;partnerlogos&#8221;][\/vc_column][vc_column top_margin=&#8221;-8%&#8221; top_margin_tablet=&#8221;0&#8243; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;lp-buehne_img&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; column_padding_type=&#8221;advanced&#8221; offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][image_with_animation image_url=&#8221;138483&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;column_reverse&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;unterBuehne_mobile&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;0px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][nectar_btn size=&#8221;jumbo&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Extra-Color-1&#8243; solid_text_color_override=&#8221;#000000&#8243; icon_family=&#8221;none&#8221; text=&#8221;Try the demo free of charge&#8221; margin_top=&#8221;30&#8243; url=&#8221;#demo&#8221;][image_with_animation image_url=&#8221;138641&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; margin_top=&#8221;20&#8243; el_class=&#8221;partnerlogos&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;column_reverse&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; left_padding_desktop=&#8221;5%&#8221; right_padding_desktop=&#8221;5%&#8221; bottom_margin=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;comparison&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;0px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;.vc_custom_1706546384693{margin-bottom: 40px !important;}&#8221;]\n<h2 style=\"text-align: center;\">WSCAD ELECTRIX ROCKET compared to other electrical CAD software<\/h2>\n[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1706546404377{margin-bottom: 40px !important;}&#8221;]\n<p style=\"text-align: center; color: red;\">Dummytabelle:<\/p>\n[\/vc_column_text][tabbed_section style=&#8221;vertical_modern&#8221; tab_color=&#8221;Accent-Color&#8221; vs_content_animation=&#8221;fade&#8221; vs_link_animation=&#8221;opacity&#8221; vs_navigation_alignment=&#8221;left&#8221; vs_navigation_width_2=&#8221;25%&#8221; vs_navigation_func=&#8221;default&#8221; vs_navigation_width=&#8221;regular&#8221; vs_navigation_spacing=&#8221;15px&#8221; vs_navigation_mobile_display=&#8221;visible&#8221; vs_tab_spacing=&#8221;5%&#8221; el_class=&#8221;vertical-tabs&#8221;][tab icon_family=&#8221;none&#8221; title=&#8221;Highlights&#8221; id=&#8221;1771927669212-8&#8243; tab_id=&#8221;1771927669213-5&#8243; sub_desc=&#8221;Subtext&#8221;][vc_column_text]\n<table class=\"vergleichstabelle\">\n<thead>\n<tr>\n<th class=\"vergleichstabelle_funktion\">Function<\/th>\n<th class=\"vergleichstabelle_nutzen\">Benefit<\/th>\n<th class=\"vergleichstabelle_wscad_ba\">WSCAD BA<\/th>\n<th class=\"vergleichstabelle_ga_software\">Other MEP software<\/th>\n<th class=\"vergleichstabelle_andere_ecad\">Other electrical<br \/>\nCAD software<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>Interdisciplinary work: BA-Schemes -&gt; installation drawing-&gt; circuit diagrams -&gt; cabinet design<\/td>\n<td>\n<ul>\n<li>Time saving<\/li>\n<li>Consistency in engineering data<\/li>\n<li>Improved quality<\/li>\n<li>No loss of information<\/li>\n<\/ul>\n<\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-check accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-times accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-times accent-color\"><\/i><\/td>\n<\/tr>\n<tr>\n<td>Free customisable datapoint addressing concep<\/td>\n<td>\n<ul>\n<li>Flexibly adjustable<\/li>\n<li>Changes and updates during project duration possible<\/li>\n<\/ul>\n<\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-check accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-times accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-times accent-color\"><\/i><\/td>\n<\/tr>\n<tr>\n<td>Working with macros<\/td>\n<td>\n<ul>\n<li>Freely configurable<\/li>\n<li>Easy to define own macros<\/li>\n<li>Variants and assignment of properties<\/li>\n<li>User-friendly interface<\/li>\n<li>Time saving<\/li>\n<\/ul>\n<\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-check accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-times accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-check accent-color\"><\/i><\/td>\n<\/tr>\n<tr>\n<td>Automatic generation of circuit diagrams and automation schemes<\/td>\n<td>\n<ul>\n<li>Construct efficiently with macros and win up to 75% time<\/li>\n<\/ul>\n<\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-check accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-times accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-check accent-color\"><\/i><\/td>\n<\/tr>\n<tr>\n<td>Own part database (local and online)<\/td>\n<td>\n<ul>\n<li>Efficient work by standardising and reusing the data<\/li>\n<\/ul>\n<\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-check accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-times accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-check accent-color\"><\/i><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n[\/vc_column_text][\/tab][tab icon_family=&#8221;none&#8221; title=&#8221;All Functions&#8221; id=&#8221;1771927669227-9&#8243; tab_id=&#8221;1771927669228-0&#8243;][vc_column_text]\n<table class=\"vergleichstabelle\">\n<thead>\n<tr>\n<th class=\"vergleichstabelle_funktion\">Function<\/th>\n<th class=\"vergleichstabelle_nutzen\">Benefit<\/th>\n<th class=\"vergleichstabelle_wscad_ba\">WSCAD BA<\/th>\n<th class=\"vergleichstabelle_ga_software\">Other MEP software<\/th>\n<th class=\"vergleichstabelle_andere_ecad\">Other electrical<br \/>\nCAD software<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>Interdisciplinary work: BA-Schemes -&gt; installation drawing-&gt; circuit diagrams -&gt; cabinet design<\/td>\n<td>\n<ul>\n<li>Time saving<\/li>\n<li>Consistency in engineering data<\/li>\n<li>Improved quality<\/li>\n<li>No loss of information<\/li>\n<\/ul>\n<\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-check accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-times accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-times accent-color\"><\/i><\/td>\n<\/tr>\n<tr>\n<td>Free customisable datapoint addressing concep<\/td>\n<td>\n<ul>\n<li>Flexibly adjustable<\/li>\n<li>Changes and updates during project duration possible<\/li>\n<\/ul>\n<\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-check accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-times accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-times accent-color\"><\/i><\/td>\n<\/tr>\n<tr>\n<td>Working with macros<\/td>\n<td>\n<ul>\n<li>Freely configurable<\/li>\n<li>Easy to define own macros<\/li>\n<li>Variants and assignment of properties<\/li>\n<li>User-friendly interface<\/li>\n<li>Time saving<\/li>\n<\/ul>\n<\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-check accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-times accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-check accent-color\"><\/i><\/td>\n<\/tr>\n<tr>\n<td>Automatic generation of circuit diagrams and automation schemes<\/td>\n<td>\n<ul>\n<li>Construct efficiently with macros and win up to 75% time<\/li>\n<\/ul>\n<\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-check accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-times accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-check accent-color\"><\/i><\/td>\n<\/tr>\n<tr>\n<td>Own part database (local and online)<\/td>\n<td>\n<ul>\n<li>Efficient work by standardising and reusing the data<\/li>\n<\/ul>\n<\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-check accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-times accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-check accent-color\"><\/i><\/td>\n<\/tr>\n<tr>\n<td>Free plant structuring acc. to IEC 8134<\/td>\n<td>\n<ul>\n<li>Clear structuring of the project<\/li>\n<li>Integration of the structure into the addressing concept<\/li>\n<\/ul>\n<\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-check accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-times accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-check accent-color\"><\/i><\/td>\n<\/tr>\n<tr>\n<td>Symbols acc. to IEC 62424 and VDI 3813 and 3814<\/td>\n<td>\n<ul>\n<li>Free and flexible construction with symbol libraries<\/li>\n<\/ul>\n<\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-check accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-times accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-times accent-color\"><\/i><\/td>\n<\/tr>\n<tr>\n<td>Generation of function lists acc. to IEC 16484<\/td>\n<td>\n<ul>\n<li>BACnet compliant presentation<\/li>\n<\/ul>\n<\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-check accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-times accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-times accent-color\"><\/i><\/td>\n<\/tr>\n<tr>\n<td>Reflection of the data points in information links<\/td>\n<td>\n<ul>\n<li>Clear assignment of the data points in the automation scheme<\/li>\n<\/ul>\n<\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-check accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-times accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-times accent-color\"><\/i><\/td>\n<\/tr>\n<tr>\n<td>Standardisation of the data points for each device<\/td>\n<td>\n<ul>\n<li>Increases the flexibility and enables fast defining of own datapoint addressing concepts<\/li>\n<\/ul>\n<\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-check accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-times accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-times accent-color\"><\/i><\/td>\n<\/tr>\n<tr>\n<td>Auto connection of devices with connection line<\/td>\n<td>\n<ul>\n<li>Intuitive construction<\/li>\n<\/ul>\n<\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-check accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-times accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-check accent-color\"><\/i><\/td>\n<\/tr>\n<tr>\n<td>Intelligent copy-and-pasteCTRL-C\/CTRL-V<\/td>\n<td>\n<ul>\n<li>Time saving<\/li>\n<li>Avoiding mistakes<\/li>\n<\/ul>\n<\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-check accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-times accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-check accent-color\"><\/i><\/td>\n<\/tr>\n<tr>\n<td>Export of smart PDF<\/td>\n<td>\n<ul>\n<li>Linked cross-references within the document<\/li>\n<\/ul>\n<\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-check accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-times accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-check accent-color\"><\/i><\/td>\n<\/tr>\n<tr>\n<td>Sheet size freely definabl<\/td>\n<td>\n<ul>\n<li>All standard paper sizes and free sheet sizes<\/li>\n<li>Predefined layout<\/li>\n<\/ul>\n<\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-check accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-times accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-check accent-color\"><\/i><\/td>\n<\/tr>\n<tr>\n<td>Import of DWG\/DXF<\/td>\n<td>\n<ul>\n<li>Easy transfer of planning data<\/li>\n<\/ul>\n<\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-check accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-times accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-check accent-color\"><\/i><\/td>\n<\/tr>\n<tr>\n<td>Import of PDF<\/td>\n<td>\n<ul>\n<li>Easy transfer of planning data<\/li>\n<\/ul>\n<\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-check accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-times accent-color\"><\/i><\/td>\n<td style=\"text-align: center;\"><i class=\"icon-default-style fa fa-check accent-color\"><\/i><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n[\/vc_column_text][\/tab][\/tabbed_section][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;column_reverse&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;3%&#8221; bottom_padding=&#8221;3%&#8221; bottom_margin=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;0px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][divider line_type=&#8221;Full Width Line&#8221; line_thickness=&#8221;1&#8243; divider_color=&#8221;default&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;column_reverse&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;3%&#8221; left_padding_desktop=&#8221;5%&#8221; right_padding_desktop=&#8221;5%&#8221; bottom_margin=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;0px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][tabbed_section style=&#8221;vertical_modern&#8221; tab_color=&#8221;Accent-Color&#8221; vs_content_animation=&#8221;fade&#8221; vs_link_animation=&#8221;opacity&#8221; vs_navigation_alignment=&#8221;left&#8221; vs_navigation_width_2=&#8221;25%&#8221; vs_navigation_func=&#8221;default&#8221; vs_navigation_width=&#8221;regular&#8221; vs_navigation_spacing=&#8221;15px&#8221; vs_navigation_mobile_display=&#8221;visible&#8221; vs_tab_spacing=&#8221;5%&#8221; el_class=&#8221;vertical-tabs&#8221;][tab icon_family=&#8221;none&#8221; title=&#8221;Save up to 70 % of your time&#8221; id=&#8221;1771927669344-1&#8243; tab_id=&#8221;1771927669345-1&#8243; sub_desc=&#8221;Subtext&#8221;][vc_row_inner column_margin=&#8221;20px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h3>Save up to 70 % of your time<\/h3>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<ul class=\"gelbe_bulletpointliste\">\n<li>Even as a beginner or casual user, you can find symbols, articles, macros in seconds with the Search &amp; Click function and insert them into the plan<\/li>\n<li>Automated schematic generation using macros \u2013 across all pages and disciplines.<\/li>\n<li>Import all your parts from the worlds&#8217; biggest electrical part database <a href=\"http:\/\/wscaduniverse.com\">wscaduniverse.com<\/a><\/li>\n<\/ul>\n[\/vc_column_text][nectar_btn size=&#8221;large&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Extra-Color-1&#8243; solid_text_color_override=&#8221;#000000&#8243; icon_family=&#8221;fontawesome&#8221; text=&#8221;Try ELECTRIX now for free!&#8221; margin_top=&#8221;30&#8243; url=&#8221;#demo&#8221; icon_fontawesome=&#8221;fa fa-play&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;135269&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; img_link_large=&#8221;yes&#8221; img_link_caption=&#8221;yes&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/tab][tab icon_family=&#8221;none&#8221; title=&#8221;Focus on your creative electrical design&#8221; id=&#8221;1771927669424-10&#8243; tab_id=&#8221;1771927669424-1&#8243;][vc_row_inner column_margin=&#8221;20px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h3>Focus on your creative electrical design<\/h3>\n[\/vc_column_text][vc_column_text]\n<ul class=\"gelbe_bulletpointliste\">\n<li>Interdisciplinary consistency and coworking between all engineering departments.<\/li>\n<li>Large drawing area and smart context menues<\/li>\n<li>Automated function list generation and evaluations<\/li>\n<\/ul>\n[\/vc_column_text][nectar_btn size=&#8221;large&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Extra-Color-1&#8243; solid_text_color_override=&#8221;#000000&#8243; icon_family=&#8221;fontawesome&#8221; text=&#8221;Try ELECTRIX now for free!&#8221; margin_top=&#8221;30&#8243; url=&#8221;#demo&#8221; icon_fontawesome=&#8221;fa fa-play&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;135262&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; img_link_large=&#8221;yes&#8221; img_link_caption=&#8221;yes&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/tab][tab icon_family=&#8221;none&#8221; title=&#8221;We are always there for you&#8221; id=&#8221;1771927669506-6&#8243; tab_id=&#8221;1771927669506-10&#8243; sub_desc=&#8221;Subtext&#8221;][vc_row_inner column_margin=&#8221;20px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h3>We are always there for you<\/h3>\n[\/vc_column_text][vc_column_text]\n<ul class=\"gelbe_bulletpointliste\">\n<li>We support you if you want to change your software, digitise diagrams or need any other professional services related to the software<\/li>\n<li>We help you with a professional onboarding in your software and your personal contact person will help you with any issues<\/li>\n<li>Intuitve to use, Search &amp; Click will help you even if you\u2019re searching for specific project settings<\/li>\n<li>Software Trainings and wordwide support for our customers<\/li>\n<\/ul>\n[\/vc_column_text][nectar_btn size=&#8221;large&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Extra-Color-1&#8243; solid_text_color_override=&#8221;#000000&#8243; icon_family=&#8221;fontawesome&#8221; text=&#8221;Try ELECTRIX now for free!&#8221; margin_top=&#8221;30&#8243; url=&#8221;#demo&#8221; icon_fontawesome=&#8221;fa fa-play&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;125988&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; img_link_large=&#8221;yes&#8221; img_link_caption=&#8221;yes&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/tab][\/tabbed_section][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;column_reverse&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;3%&#8221; bottom_padding=&#8221;60&#8243; bottom_margin=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;0px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][vc_column_text]\n<h2 style=\"text-align: center;\">Six engineering disciplines in one software<\/h2>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;disziplinen&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;left-right&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;reveal-from-left&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;50&#8243;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;disziplin_icon&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;111249&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/vc_column_inner][vc_column_inner left_padding_desktop=&#8221;3%&#8221; bottom_padding_tablet=&#8221;16px&#8221; left_padding_tablet=&#8221;0&#8243; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;disziplin_text&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;4\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; column_padding_type=&#8221;advanced&#8221;][vc_column_text]\n<h3>Electrical Engineering<\/h3>\n<p><strong>Wiring diagram design<\/strong><br \/>\nThe Electrical Engineering module in WSCAD ELECTRIX enables you to design medium and low voltage systems for machines, plants, industrial automation and building automation.<br \/>\n<div class=\"show_more\"><p class=\"wpsm-show\" style=\"color: #cc0000; font-size: 100%; text-align: left;\"> Read more<\/p><div class=\"wpsm-content\">Control cabinet designers, facility managers, maintenance engineers and industrial electricians rely on our user-friendly software to handle electrical schematics, control cabinets and all according documents.<br \/>\n<a href=\"https:\/\/www.wscad.com\/en\/engineering-disciplines\/electrical-engineering\/\" target=\"_blank\" rel=\"noopener\"><strong>Learn more<\/strong><\/a> <p class=\"wpsm-hide\" style=\"color: #cc0000; font-size: 100%; text-align: left;\"> Close<\/p><\/div><\/div>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;left-right&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;reveal-from-right&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;700&#8243;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;disziplin_icon&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;111242&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/vc_column_inner][vc_column_inner left_padding_desktop=&#8221;3%&#8221; bottom_padding_tablet=&#8221;16px&#8221; left_padding_tablet=&#8221;0&#8243; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;disziplin_text&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;4\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; column_padding_type=&#8221;advanced&#8221;][vc_column_text]\n<h3>Cabinet Engineering<\/h3>\n<p><strong>Professional cabinet design and wire routing<\/strong><br \/>\nWith the WSCAD ELECTRIX Cabinet Engineering module designing panels is super easy: use the precise and optimal placement of components, collision checks or the calculation of wire lengths\/routes \u2013 all of this available during the design phase.<div class=\"show_more\"><p class=\"wpsm-show\" style=\"color: #cc0000; font-size: 100%; text-align: left;\"> Read more<\/p><div class=\"wpsm-content\">Drilling data for components, mounting rails and cable trays can be configured easily through a dedicated menu. The integrated 3D view of the cabinet gives you a better spatial awareness.<br \/>\n<a href=\"https:\/\/www.wscad.com\/en\/engineering-disciplines\/cabinet-engineering\/\" target=\"_blank\" rel=\"noopener\"><strong>Learn more<\/strong><\/a> <p class=\"wpsm-hide\" style=\"color: #cc0000; font-size: 100%; text-align: left;\"> Close<\/p><\/div><\/div>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;disziplinen&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;left-right&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;reveal-from-left&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;50&#8243; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;disziplin_icon&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;111277&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/vc_column_inner][vc_column_inner left_padding_desktop=&#8221;3%&#8221; bottom_padding_tablet=&#8221;16px&#8221; left_padding_tablet=&#8221;0&#8243; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;disziplin_text&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;4\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; column_padding_type=&#8221;advanced&#8221;][vc_column_text]\n<h3>Piping &amp; Instrumentation<\/h3>\n<p><strong>Process engineering and measuring point management<\/strong><br \/>\nDesign piping and instrumentation diagrams easily using WSCAD ELECTRIX P&amp;ID (Piping &amp; Instrumentation Diagrams) module.<br \/>\n<div class=\"show_more\"><p class=\"wpsm-show\" style=\"color: #cc0000; font-size: 100%; text-align: left;\"> Read more<\/p><div class=\"wpsm-content\">By linking every P&amp;ID component with their representation in another engineering discipline you get a consistent design. Add the unique, sequential numbering of measuring points and you will be able to remove errors in a breeze.<br \/>\n<a href=\"https:\/\/www.wscad.com\/en\/engineering-disciplines\/piping-instrumentation\/\" target=\"_blank\" rel=\"noopener\"><strong>Learn more<\/strong><\/a> <p class=\"wpsm-hide\" style=\"color: #cc0000; font-size: 100%; text-align: left;\"> Close<\/p><\/div><\/div>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;left-right&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;reveal-from-right&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;700&#8243; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;disziplin_icon&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;111263&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/vc_column_inner][vc_column_inner left_padding_desktop=&#8221;3%&#8221; bottom_padding_tablet=&#8221;16px&#8221; left_padding_tablet=&#8221;0&#8243; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;disziplin_text&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;4\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; column_padding_type=&#8221;advanced&#8221;][vc_column_text]\n<h3>Fluid Engineering<\/h3>\n<p><strong>Pneumatic and hydraulic systems<\/strong><br \/>\nWSCAD ELECTRIX is your ideal companion to design pneumatic and hydraulic systems.<br \/>\n<div class=\"show_more\"><p class=\"wpsm-show\" style=\"color: #cc0000; font-size: 100%; text-align: left;\"> Read more<\/p><div class=\"wpsm-content\">The Fluid Engineering discipline includes all the benefits of the Electrical Engineering module, plus special fluid functions. Designers and maintenance engineers get all the tools they need for the end-to-end design of mechatronic tasks \u2013 quickly, intuitively and efficiently.<br \/>\n<a href=\"https:\/\/www.wscad.com\/en\/engineering-disciplines\/fluid-engineering\/\" target=\"_blank\" rel=\"noopener\"><strong>Learn more<\/strong><\/a> <p class=\"wpsm-hide\" style=\"color: #cc0000; font-size: 100%; text-align: left;\"> Close<\/p><\/div><\/div>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;disziplinen&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;left-right&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;reveal-from-left&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;50&#8243;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;disziplin_icon&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;111235&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/vc_column_inner][vc_column_inner left_padding_desktop=&#8221;3%&#8221; bottom_padding_tablet=&#8221;16px&#8221; left_padding_tablet=&#8221;0&#8243; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;disziplin_text&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;4\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; column_padding_type=&#8221;advanced&#8221;][vc_column_text]\n<h3>Building Automation<\/h3>\n<p><strong>Building Automation and measurement control technology<\/strong><br \/>\nDesign layouts and schematics for measurement control technology using the WSCAD ELECTRIX Building Automation module.<br \/>\n<div class=\"show_more\"><p class=\"wpsm-show\" style=\"color: #cc0000; font-size: 100%; text-align: left;\"> Read more<\/p><div class=\"wpsm-content\">Symbols placed in the schematics are linked to the corresponding component and its manufacturer data. This way you can easily generate the BOM for procurement, pricing and manufacturing. You can ensure constant transparency and traceability throughout the entire project. Just rely on the coloured representation of plant schematics and functional diagrams with subsequent evaluation of all functions, materials, field devices and cables.<br \/>\n<a href=\"https:\/\/www.wscad.com\/en\/engineering-disciplines\/building-automation\/\" target=\"_blank\" rel=\"noopener\"><strong>Learn more<\/strong><\/a> <p class=\"wpsm-hide\" style=\"color: #cc0000; font-size: 100%; text-align: left;\"> Close<\/p><\/div><\/div>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;left-right&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;reveal-from-right&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;700&#8243;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;disziplin_icon&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;111256&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/vc_column_inner][vc_column_inner left_padding_desktop=&#8221;3%&#8221; bottom_padding_tablet=&#8221;16px&#8221; left_padding_tablet=&#8221;0&#8243; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;disziplin_text&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;4\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; column_padding_type=&#8221;advanced&#8221;][vc_column_text]\n<h3>Electrical Installation<\/h3>\n<p><strong>Installation diagrams and distribution planning<\/strong><br \/>\nDesign building system technology, medium- and low-voltage installations, as well as antenna and fire alarm systems.<br \/>\n<div class=\"show_more\"><p class=\"wpsm-show\" style=\"color: #cc0000; font-size: 100%; text-align: left;\"> Read more<\/p><div class=\"wpsm-content\">The Electrical Installation module of WSCAD ELECTRIX is your tool from design to delivery, including the 3D location of equipment in plants and buildings. Import PDF or DWG floor plans at scale, place all the field devices and link them to the existing symbol data of the schematics.<br \/>\n<a href=\"https:\/\/www.wscad.com\/en\/engineering-disciplines\/electrical-installation\/\" target=\"_blank\" rel=\"noopener\"><strong>Learn more<\/strong><\/a> <p class=\"wpsm-hide\" style=\"color: #cc0000; font-size: 100%; text-align: left;\"> Close<\/p><\/div><\/div>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#10263b&#8221; scene_position=&#8221;center&#8221; bottom_margin=&#8221;0&#8243; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][vc_column_text]\n<h2 style=\"text-align: center;\">Over 40,000 customers work with WSCAD<\/h2>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;3%&#8221; bottom_padding=&#8221;3%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column top_padding_desktop=&#8221;5%&#8221; bottom_padding_desktop=&#8221;5%&#8221; left_padding_desktop=&#8221;2%&#8221; right_padding_desktop=&#8221;2%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;left&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#f2f2f2&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][testimonial_slider style=&#8221;default&#8221; star_rating_color=&#8221;accent-color&#8221; autorotate=&#8221;5000&#8243; disable_height_animation=&#8221;true&#8221;][testimonial star_rating=&#8221;none&#8221; title=&#8221;Testimonial&#8221; id=&#8221;1771927670186-1&#8243; tab_id=&#8221;1771927670186-9&#8243; href=&#8221;\/\/www.cummins.com\/&#8220;&#8221; target=&#8221;&#8220;_blank&#8220;&#8221; subtitle=&#8221;Sebastian Michels Alfaro<br \/>\n(Electrical Engineering Group Leader)&#8221; name=&#8221;Cummins Inc.&#8221; quote=&#8221;We decided to replace AutoCAD Electrical and EPLAN and standardise our global electrical design on WSCAD software as it combines the advanced capabilities of EPLAN with ease of use. Our engineers are able to learn the software very quickly and use efficient engineering workflows through the explorers provided by the tool.&#8221;][testimonial star_rating=&#8221;none&#8221; title=&#8221;Testimonial&#8221; id=&#8221;1771927670204-3&#8243; tab_id=&#8221;1771927670205-6&#8243; href=&#8221;\/\/www.cummins.com\/&#8220;&#8221; target=&#8221;&#8220;_blank&#8220;&#8221; subtitle=&#8221;Alexander Krahner (Administrator CAE Applications)&#8221; name=&#8221;WAGO GmbH &amp; Co. KG&#8221; quote=&#8221;This software has changed the way I work and helped me to work more efficiently and precisely.<br \/>\nI highly recommend it to any electrical engineer or designer. Try it out and see for yourself how WSCAD ELECTRIX can make your working life easier!&#8221;][testimonial star_rating=&#8221;none&#8221; title=&#8221;Testimonial&#8221; id=&#8221;1771927670217-9&#8243; tab_id=&#8221;1771927670217-6&#8243; href=&#8221;\/\/www.cummins.com\/&#8220;&#8221; target=&#8221;&#8220;_blank&#8220;&#8221; name=&#8221;TROX HGI GmbH&#8221; quote=&#8221;WSCAD ELECTRIX has impressed from the very beginning. The newly developed editor in particular represents a very good further development from which all customers benefit.&#8221;][\/testimonial_slider][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text el_class=&#8221;rating small&#8221;]\n<h4>Top rated electrical CAD Software!<\/h4>\n<table>\n<tbody>\n<tr>\n<td><strong>Google<\/strong><br \/>\n<span class=\"stars\"><i class=\"icon-tiny fa fa-star extra-color-1\"><\/i><i class=\"icon-tiny fa fa-star extra-color-1\"><\/i><i class=\"icon-tiny fa fa-star extra-color-1\"><\/i><i class=\"icon-tiny fa fa-star extra-color-1\"><\/i><i class=\"icon-tiny fa fa-star extra-color-1\"><\/i><\/span> 4,8<\/td>\n<td><strong>Capterra<\/strong><br \/>\n<span class=\"stars\"><i class=\"icon-tiny fa fa-star extra-color-1\"><\/i><i class=\"icon-tiny fa fa-star extra-color-1\"><\/i><i class=\"icon-tiny fa fa-star extra-color-1\"><\/i><i class=\"icon-tiny fa fa-star extra-color-1\"><\/i><i class=\"icon-tiny fa fa-star extra-color-1\"><\/i><\/span> 5,0<\/td>\n<td><strong>GetApp<\/strong><br \/>\n<span class=\"stars\"><i class=\"icon-tiny fa fa-star extra-color-1\"><\/i><i class=\"icon-tiny fa fa-star extra-color-1\"><\/i><i class=\"icon-tiny fa fa-star extra-color-1\"><\/i><i class=\"icon-tiny fa fa-star extra-color-1\"><\/i><i class=\"icon-tiny fa fa-star extra-color-1\"><\/i><\/span> 5,0<\/td>\n<td><strong>SourceForge<\/strong><br \/>\n<span class=\"stars\"><i class=\"icon-tiny fa fa-star extra-color-1\"><\/i><i class=\"icon-tiny fa fa-star extra-color-1\"><\/i><i class=\"icon-tiny fa fa-star extra-color-1\"><\/i><i class=\"icon-tiny fa fa-star extra-color-1\"><\/i><i class=\"icon-tiny fa fa-star extra-color-1\"><\/i><\/span> 5,0<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n[\/vc_column_text][image_with_animation image_url=&#8221;132548&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; el_class=&#8221;award&#8221; margin_top=&#8221;20&#8243;][vc_column_text css_animation=&#8221;none&#8221; css=&#8221;.vc_custom_1705580564464{margin-top: 30px !important;margin-bottom: 8px !important;}&#8221;]\n<h4>WSCAD Facts<\/h4>\n[\/vc_column_text][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; el_id=&#8221;facts&#8221; css=&#8221;.vc_custom_1705580227884{margin-bottom: 0px !important;}&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; delay=&#8221;100&#8243;][image_with_animation image_url=&#8221;137701&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; el_class=&#8221;facticon&#8221;][vc_column_text css_animation=&#8221;none&#8221;]\n<h3>&gt; 40,000<\/h3>\n<p>users[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; delay=&#8221;200&#8243;][image_with_animation image_url=&#8221;137708&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; el_class=&#8221;facticon&#8221;][vc_column_text css_animation=&#8221;none&#8221;]\n<h3>&gt; 35 years<\/h3>\n<p>of ongoing market success[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; delay=&#8221;300&#8243;][image_with_animation image_url=&#8221;137715&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; el_class=&#8221;facticon&#8221;][vc_column_text css_animation=&#8221;none&#8221;]\n<h3>&gt; 100<\/h3>\n<p>countries use WSCAD[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#f2f2f2&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;3%&#8221; bottom_padding=&#8221;3%&#8221; top_margin=&#8221;3%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; disable_element=&#8221;yes&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;.vc_custom_1686124563061{margin-bottom: 30px !important;}&#8221;]\n<h3>Mit WSCAD ELECTRIX kostenloser Zugriff auf die weltweit gr\u00f6\u00dfte E-CAD-Datenbibliothek<\/h3>\n[\/vc_column_text][vc_column_text]\n<h4>Ganz einfach 2.2 Mio. Artikel aus wscaduniverse.com nutzen<\/h4>\n<p>Die Artikeldatenbank <a href=\"https:\/\/wscaduniverse.com\/\" target=\"_blank\" rel=\"noopener\">wscaduniverse.com<\/a> ist Bestandteil von WSCAD ELECTRIX. Anstatt Artikel h\u00e4ndisch zu erstellen, setzen Sie kostenlos \u00fcber 2.2 Mio. Artikel von 450 Herstellern direkt in WSCAD ELECTRIX ein. Durch die artikelorientierte Arbeitsweise wird mit einem Klick das Symbol aus der Artikelauswahl geladen und die zugeh\u00f6rigen Artikeldaten im Plan hinterlegt. In der Artikeldatenbank kann zu jedem Bauteil das passende Symbol verlinkt werden. Die Artikeldaten in <a href=\"https:\/\/wscaduniverse.com\/\" target=\"_blank\" rel=\"noopener\">wscaduniverse.com<\/a> werden monatlich aktualisiert.[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;120428&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;column_reverse&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;3%&#8221; bottom_margin=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;0px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][divider line_type=&#8221;Full Width Line&#8221; line_thickness=&#8221;1&#8243; divider_color=&#8221;default&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;demo&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;.vc_custom_1705578627870{margin-bottom: 40px !important;}&#8221;]\n<h2 style=\"text-align: center;\">Get the ELECTRIX ROCKET demo version<\/h2>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;3%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;.vc_custom_1705578606721{margin-bottom: 20px !important;}&#8221;]\n<h3>Try now the latest version of the E-CAD software from WSCAD for free<\/h3>\n[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1771497057188{margin-bottom: 20px !important;}&#8221; text_direction=&#8221;default&#8221;]Get the complete <a href=\"https:\/\/www.wscad.com\/en\/?page_id=112122\">WSCAD ELECTRIX<\/a> demo and try it, including all the modules for free. Simply fill in the form and we will send you an email with the download link of the WSCAD ELECTRIX demo version.[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1705579063256{margin-bottom: 30px !important;}&#8221;]<strong>What you can expect:<\/strong><\/p>\n<ul class=\"gelbe_bulletpointliste\">\n<li>Test all functions for 30 days without obligation<\/li>\n<li>Highest expansion level of the software with all six electrical design disciplines<\/li>\n<li>Addon &#8220;ProjectWizard&#8221; pre-installed<\/li>\n<li>Completely free of charge &#8211; no credit card details required<\/li>\n<\/ul>\n[\/vc_column_text][divider line_type=&#8221;Full Width Line&#8221; line_thickness=&#8221;1&#8243; divider_color=&#8221;default&#8221;][vc_column_text css=&#8221;.vc_custom_1705582688820{margin-top: 30px !important;margin-bottom: -10px !important;}&#8221;]\n<h4>If you would like a personal consultation:<\/h4>\n[\/vc_column_text][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_raw_html]JTVCaWZzbyUyMGlkJTNEJTIyMTM1NjQ4JTIyJTVE[\/vc_raw_html][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column top_padding_desktop=&#8221;20px&#8221; bottom_padding_desktop=&#8221;20px&#8221; left_padding_desktop=&#8221;20px&#8221; right_padding_desktop=&#8221;20px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#f2f2f2&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][vc_column_text]\n\t\t\t\t\t\t<script>\n\t\t\t\t\t\t\twindow.hsFormsOnReady = window.hsFormsOnReady || [];\n\t\t\t\t\t\t\twindow.hsFormsOnReady.push(()=>{\n\t\t\t\t\t\t\t\thbspt.forms.create({\n\t\t\t\t\t\t\t\t\tportalId: 26653386,\n\t\t\t\t\t\t\t\t\tformId: \"c7b99a2e-250c-4cdb-87c4-0cf93908812f\",\n\t\t\t\t\t\t\t\t\ttarget: \"#hbspt-form-1778708056000-8861953373\",\n\t\t\t\t\t\t\t\t\tregion: \"eu1\",\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t})});\n\t\t\t\t\t\t<\/script>\n\t\t\t\t\t\t<div class=\"hbspt-form\" id=\"hbspt-form-1778708056000-8861953373\"><\/div>[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;0&#8243; bottom_margin=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column top_padding_desktop=&#8221;8%&#8221; left_padding_desktop=&#8221;10%&#8221; top_padding_tablet=&#8221;5%&#8221; bottom_padding_tablet=&#8221;5%&#8221; left_padding_tablet=&#8221;5%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;0px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221;&#8230;<\/p>\n","protected":false},"author":48,"featured_media":131832,"parent":138713,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"content-type":"","inline_featured_image":false,"footnotes":""},"class_list":["post-139046","page","type-page","status-publish","has-post-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Electrical CAD software comparsion | WSCAD GmbH<\/title>\n<meta name=\"description\" content=\"One electrical design software for everything - Electrical Engineering, Cabinet Engineering, Piping &amp; Instrumentation, Fluid Engineering...\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Electrical CAD software comparsion | WSCAD GmbH\" \/>\n<meta property=\"og:description\" content=\"One electrical design software for everything - Electrical Engineering, Cabinet Engineering, Piping &amp; Instrumentation, Fluid Engineering...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wscad.com\/en\/lp\/electrical-cad-software-comparsion\/\" \/>\n<meta property=\"og:site_name\" content=\"WSCAD GmbH\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-24T12:19:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.wscad.com\/wp-content\/uploads\/2023\/02\/WEB_Holo-02-BA-ANW_tab-2023-03.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"617\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@wscad\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"TechArticle\",\"@id\":\"https:\/\/www.wscad.com\/en\/lp\/electrical-cad-software-comparsion\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.wscad.com\/en\/lp\/electrical-cad-software-comparsion\/\"},\"author\":{\"name\":\"Alex Vell\",\"@id\":\"https:\/\/www.wscad.com\/en\/#\/schema\/person\/062e798bd850a5d12170c1e8ae712a0f\"},\"headline\":\"Electrical CAD software comparsion\",\"datePublished\":\"2024-01-29T16:22:55+00:00\",\"dateModified\":\"2026-02-24T12:19:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.wscad.com\/en\/lp\/electrical-cad-software-comparsion\/\"},\"wordCount\":10014,\"publisher\":{\"@id\":\"https:\/\/www.wscad.com\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.wscad.com\/en\/lp\/electrical-cad-software-comparsion\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.wscad.com\/wp-content\/uploads\/2023\/02\/WEB_Holo-02-BA-ANW_tab-2023-03.jpg\",\"articleSection\":[\"Ad-Landingpage\",\"KeineSuche\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.wscad.com\/en\/lp\/electrical-cad-software-comparsion\/\",\"url\":\"https:\/\/www.wscad.com\/en\/lp\/electrical-cad-software-comparsion\/\",\"name\":\"Electrical CAD software comparsion | WSCAD GmbH\",\"isPartOf\":{\"@id\":\"https:\/\/www.wscad.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.wscad.com\/en\/lp\/electrical-cad-software-comparsion\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.wscad.com\/en\/lp\/electrical-cad-software-comparsion\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.wscad.com\/wp-content\/uploads\/2023\/02\/WEB_Holo-02-BA-ANW_tab-2023-03.jpg\",\"datePublished\":\"2024-01-29T16:22:55+00:00\",\"dateModified\":\"2026-02-24T12:19:06+00:00\",\"description\":\"One electrical design software for everything - Electrical Engineering, Cabinet Engineering, Piping & Instrumentation, Fluid Engineering...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.wscad.com\/en\/lp\/electrical-cad-software-comparsion\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.wscad.com\/en\/lp\/electrical-cad-software-comparsion\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.wscad.com\/en\/lp\/electrical-cad-software-comparsion\/#primaryimage\",\"url\":\"https:\/\/www.wscad.com\/wp-content\/uploads\/2023\/02\/WEB_Holo-02-BA-ANW_tab-2023-03.jpg\",\"contentUrl\":\"https:\/\/www.wscad.com\/wp-content\/uploads\/2023\/02\/WEB_Holo-02-BA-ANW_tab-2023-03.jpg\",\"width\":1200,\"height\":617},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.wscad.com\/en\/lp\/electrical-cad-software-comparsion\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Ad Landingpages\",\"item\":\"https:\/\/www.wscad.com\/en\/lp\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Electrical CAD software comparsion\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.wscad.com\/en\/#website\",\"url\":\"https:\/\/www.wscad.com\/en\/\",\"name\":\"WSCAD GmbH\",\"description\":\"The only AI-powered electrical CAD\",\"publisher\":{\"@id\":\"https:\/\/www.wscad.com\/en\/#organization\"},\"alternateName\":\"Electrical CAD Software\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.wscad.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.wscad.com\/en\/#organization\",\"name\":\"WSCAD GmbH\",\"alternateName\":\"ELECTRIX\",\"url\":\"https:\/\/www.wscad.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.wscad.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.wscad.com\/wp-content\/uploads\/2024\/10\/WSCAD-Logo-4c_Positive-Blue-RGB_frameless.png\",\"contentUrl\":\"https:\/\/www.wscad.com\/wp-content\/uploads\/2024\/10\/WSCAD-Logo-4c_Positive-Blue-RGB_frameless.png\",\"width\":2000,\"height\":392,\"caption\":\"WSCAD GmbH\"},\"image\":{\"@id\":\"https:\/\/www.wscad.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/wscad\",\"https:\/\/www.instagram.com\/wscad_gmbh\",\"https:\/\/www.linkedin.com\/company\/wscad\/\",\"https:\/\/www.youtube.com\/c\/WSCADGmbH\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.wscad.com\/en\/#\/schema\/person\/062e798bd850a5d12170c1e8ae712a0f\",\"name\":\"Alex Vell\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Electrical CAD software comparsion | WSCAD GmbH","description":"One electrical design software for everything - Electrical Engineering, Cabinet Engineering, Piping & Instrumentation, Fluid Engineering...","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"en_GB","og_type":"article","og_title":"Electrical CAD software comparsion | WSCAD GmbH","og_description":"One electrical design software for everything - Electrical Engineering, Cabinet Engineering, Piping & Instrumentation, Fluid Engineering...","og_url":"https:\/\/www.wscad.com\/en\/lp\/electrical-cad-software-comparsion\/","og_site_name":"WSCAD GmbH","article_modified_time":"2026-02-24T12:19:06+00:00","og_image":[{"width":1200,"height":617,"url":"https:\/\/www.wscad.com\/wp-content\/uploads\/2023\/02\/WEB_Holo-02-BA-ANW_tab-2023-03.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@wscad","twitter_misc":{"Estimated reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"TechArticle","@id":"https:\/\/www.wscad.com\/en\/lp\/electrical-cad-software-comparsion\/#article","isPartOf":{"@id":"https:\/\/www.wscad.com\/en\/lp\/electrical-cad-software-comparsion\/"},"author":{"name":"Alex Vell","@id":"https:\/\/www.wscad.com\/en\/#\/schema\/person\/062e798bd850a5d12170c1e8ae712a0f"},"headline":"Electrical CAD software comparsion","datePublished":"2024-01-29T16:22:55+00:00","dateModified":"2026-02-24T12:19:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.wscad.com\/en\/lp\/electrical-cad-software-comparsion\/"},"wordCount":10014,"publisher":{"@id":"https:\/\/www.wscad.com\/en\/#organization"},"image":{"@id":"https:\/\/www.wscad.com\/en\/lp\/electrical-cad-software-comparsion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wscad.com\/wp-content\/uploads\/2023\/02\/WEB_Holo-02-BA-ANW_tab-2023-03.jpg","articleSection":["Ad-Landingpage","KeineSuche"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.wscad.com\/en\/lp\/electrical-cad-software-comparsion\/","url":"https:\/\/www.wscad.com\/en\/lp\/electrical-cad-software-comparsion\/","name":"Electrical CAD software comparsion | WSCAD GmbH","isPartOf":{"@id":"https:\/\/www.wscad.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.wscad.com\/en\/lp\/electrical-cad-software-comparsion\/#primaryimage"},"image":{"@id":"https:\/\/www.wscad.com\/en\/lp\/electrical-cad-software-comparsion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wscad.com\/wp-content\/uploads\/2023\/02\/WEB_Holo-02-BA-ANW_tab-2023-03.jpg","datePublished":"2024-01-29T16:22:55+00:00","dateModified":"2026-02-24T12:19:06+00:00","description":"One electrical design software for everything - Electrical Engineering, Cabinet Engineering, Piping & Instrumentation, Fluid Engineering...","breadcrumb":{"@id":"https:\/\/www.wscad.com\/en\/lp\/electrical-cad-software-comparsion\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wscad.com\/en\/lp\/electrical-cad-software-comparsion\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.wscad.com\/en\/lp\/electrical-cad-software-comparsion\/#primaryimage","url":"https:\/\/www.wscad.com\/wp-content\/uploads\/2023\/02\/WEB_Holo-02-BA-ANW_tab-2023-03.jpg","contentUrl":"https:\/\/www.wscad.com\/wp-content\/uploads\/2023\/02\/WEB_Holo-02-BA-ANW_tab-2023-03.jpg","width":1200,"height":617},{"@type":"BreadcrumbList","@id":"https:\/\/www.wscad.com\/en\/lp\/electrical-cad-software-comparsion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Ad Landingpages","item":"https:\/\/www.wscad.com\/en\/lp\/"},{"@type":"ListItem","position":2,"name":"Electrical CAD software comparsion"}]},{"@type":"WebSite","@id":"https:\/\/www.wscad.com\/en\/#website","url":"https:\/\/www.wscad.com\/en\/","name":"WSCAD GmbH","description":"The only AI-powered electrical CAD","publisher":{"@id":"https:\/\/www.wscad.com\/en\/#organization"},"alternateName":"Electrical CAD Software","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wscad.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.wscad.com\/en\/#organization","name":"WSCAD GmbH","alternateName":"ELECTRIX","url":"https:\/\/www.wscad.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.wscad.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.wscad.com\/wp-content\/uploads\/2024\/10\/WSCAD-Logo-4c_Positive-Blue-RGB_frameless.png","contentUrl":"https:\/\/www.wscad.com\/wp-content\/uploads\/2024\/10\/WSCAD-Logo-4c_Positive-Blue-RGB_frameless.png","width":2000,"height":392,"caption":"WSCAD GmbH"},"image":{"@id":"https:\/\/www.wscad.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/wscad","https:\/\/www.instagram.com\/wscad_gmbh","https:\/\/www.linkedin.com\/company\/wscad\/","https:\/\/www.youtube.com\/c\/WSCADGmbH"]},{"@type":"Person","@id":"https:\/\/www.wscad.com\/en\/#\/schema\/person\/062e798bd850a5d12170c1e8ae712a0f","name":"Alex Vell"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.wscad.com\/en\/wp-json\/wp\/v2\/pages\/139046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wscad.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.wscad.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.wscad.com\/en\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wscad.com\/en\/wp-json\/wp\/v2\/comments?post=139046"}],"version-history":[{"count":9,"href":"https:\/\/www.wscad.com\/en\/wp-json\/wp\/v2\/pages\/139046\/revisions"}],"predecessor-version":[{"id":153276,"href":"https:\/\/www.wscad.com\/en\/wp-json\/wp\/v2\/pages\/139046\/revisions\/153276"}],"up":[{"embeddable":true,"href":"https:\/\/www.wscad.com\/en\/wp-json\/wp\/v2\/pages\/138713"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wscad.com\/en\/wp-json\/wp\/v2\/media\/131832"}],"wp:attachment":[{"href":"https:\/\/www.wscad.com\/en\/wp-json\/wp\/v2\/media?parent=139046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}